{"id":71658,"date":"2022-03-31T17:23:28","date_gmt":"2022-03-31T15:23:28","guid":{"rendered":"https:\/\/rhinolands.com\/post\/como-crear-una-pradera-de-flores-silvestres\/"},"modified":"2022-07-05T13:13:30","modified_gmt":"2022-07-05T11:13:30","slug":"como-crear-una-pradera-de-flores-silvestres","status":"publish","type":"post","link":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/","title":{"rendered":"C\u00f3mo crear una pradera de flores silvestres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las flores silvestres aportan belleza natural al paisaje. Las flores silvestres aportan belleza natural al paisaje. En general, un espacio amplio y soleado es el mejor lugar para crear una pradera de flores silvestres.<\/p>\n\n<p class=\"wp-block-paragraph\">La gran combinaci\u00f3n de especies vegetales con diferentes colores y texturas, atraen a las mariposas y abejas al jard\u00edn. La facilidad de implementaci\u00f3n y las pocas necesidades de mantenimiento de este tipo de paisaje silvestre son otras de las razones que pueden motivarle a a\u00f1adirlo a sus proyectos de paisajismo.\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"483\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/wildflower-meadow-modelled-with-Lands-Design-1024x483.jpg\" alt=\"\" class=\"wp-image-71519\" srcset=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/wildflower-meadow-modelled-with-Lands-Design-980x462.jpg 980w, https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/wildflower-meadow-modelled-with-Lands-Design-480x227.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><figcaption><em>Una pradera de flores silvestres modelada con Lands Design creada para el clima mediterr\u00e1neo mediante la combinaci\u00f3n de 8 especies de plantas<br\/><\/em><\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">En Lands Design hay cientos de plantas herb\u00e1ceas y c\u00e9spedes que puede seleccionar. En  la base de datos de plantas, puede aplicar filtros para seleccionar las plantas adecuadas teniendo en cuenta su zona clim\u00e1tica, el tipo de suelo, el color de las flores, etc. Puede modelar una pradera de flores silvestres f\u00e1cilmente con Lands Design siguiendo estos pasos:<\/p>\n\n<ul class=\"wp-block-list\"><li>Ejecute el comando <strong>laBosque<\/strong>, seleccione una especie de planta, introduzca una distancia m\u00ednima entre plantas, indique un l\u00edmite e inserte el bosque. <\/li><li>Seleccione el bosque haciendo clic en su geometr\u00eda y, a continuaci\u00f3n, en el panel de edici\u00f3n de Lands Design, seleccione Combinar elementos. Puede a\u00f1adir el n\u00famero de elementos (especies)  alcanzar la diversidad deseada (4 elementos como m\u00ednimo). En la parte superior del panel de edici\u00f3n, ver\u00e1 que el bosque est\u00e1 dividido en varios grupos de la misma especie de planta. Seleccione estos grupos, uno por uno, y as\u00edgneles una especie de planta diferente.<\/li><li>Si no le gusta la distribuci\u00f3n aleatoria, puede \u00abredistribuirla\u00bb desde la opci\u00f3n correspondiente en el panel de edici\u00f3n &gt; Bosque (parte superior derecha).<\/li><li>Por \u00faltimo, recuerde que puede modificar f\u00e1cilmente la combinaci\u00f3n de especies de plantas, la distancia y todas las caracter\u00edsticas desde el  panel de edici\u00f3n.<\/li><\/ul>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2-1024x576.png\" alt=\"\" class=\"wp-image-71559\" srcset=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2-980x551.png 980w, https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><figcaption><em>Proyecto final de pradera de flores silvestres: modelado con Lands Design y renderizado con Twinmotion<br\/><br\/><\/em><\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Si quiere obtener m\u00e1s informaci\u00f3n sobre las praderas de flores silvestres y las especies de plantas adecuadas, <strong>lea este <a href=\"https:\/\/www.gardeningknowhow.com\/ornamental\/flowers\/fgen\/the-wild-side-of-gardening-using-wildflowers-and-native-plants.htm\">art\u00edculo<\/a><\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las flores silvestres aportan belleza natural al paisaje. Las flores silvestres aportan belleza natural al paisaje. En general, un espacio amplio y soleado es el mejor lugar para crear una pradera de flores silvestres. La gran combinaci\u00f3n de especies vegetales con diferentes colores y texturas, atraen a las mariposas y abejas al jard\u00edn. La facilidad [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":71660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2208,2195,2046],"tags":[],"class_list":["post-71658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-es","category-formacion","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo crear una pradera de flores silvestres - RhinoLands<\/title>\n<meta name=\"description\" content=\"C\u00f3mo crear una pradera de flores silvestres en su proyecto paisaj\u00edstico o jard\u00edn. Lands Design puede modelar su pradera en 3D y proporcionar la lista de plantas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo crear una pradera de flores silvestres - RhinoLands\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo crear una pradera de flores silvestres en su proyecto paisaj\u00edstico o jard\u00edn. Lands Design puede modelar su pradera en 3D y proporcionar la lista de plantas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/\" \/>\n<meta property=\"og:site_name\" content=\"RhinoLands\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-31T15:23:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-05T11:13:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elham Ghabouli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elham Ghabouli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/\"},\"author\":{\"name\":\"Elham Ghabouli\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\"},\"headline\":\"C\u00f3mo crear una pradera de flores silvestres\",\"datePublished\":\"2022-03-31T15:23:28+00:00\",\"dateModified\":\"2022-07-05T11:13:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/\"},\"wordCount\":377,\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/TMScreenshot_2021.12.30-16.42.25-2.png\",\"articleSection\":[\"Conocimientos\",\"formaci\u00f3n\",\"Proyectos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/\",\"name\":\"C\u00f3mo crear una pradera de flores silvestres - RhinoLands\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/TMScreenshot_2021.12.30-16.42.25-2.png\",\"datePublished\":\"2022-03-31T15:23:28+00:00\",\"dateModified\":\"2022-07-05T11:13:30+00:00\",\"description\":\"C\u00f3mo crear una pradera de flores silvestres en su proyecto paisaj\u00edstico o jard\u00edn. Lands Design puede modelar su pradera en 3D y proporcionar la lista de plantas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/TMScreenshot_2021.12.30-16.42.25-2.png\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/TMScreenshot_2021.12.30-16.42.25-2.png\",\"width\":1424,\"height\":801,\"caption\":\"How to create a wildflower meadow? Lands design landscape 3D design. plant species for meadow\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/post\\\/como-crear-una-pradera-de-flores-silvestres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo crear una pradera de flores silvestres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/\",\"name\":\"RhinoLands\",\"description\":\"BIM landscape software\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#organization\",\"name\":\"Asuni Soft\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"width\":151,\"height\":46,\"caption\":\"Asuni Soft\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/es\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\",\"name\":\"Elham Ghabouli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"caption\":\"Elham Ghabouli\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo crear una pradera de flores silvestres - RhinoLands","description":"C\u00f3mo crear una pradera de flores silvestres en su proyecto paisaj\u00edstico o jard\u00edn. Lands Design puede modelar su pradera en 3D y proporcionar la lista de plantas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo crear una pradera de flores silvestres - RhinoLands","og_description":"C\u00f3mo crear una pradera de flores silvestres en su proyecto paisaj\u00edstico o jard\u00edn. Lands Design puede modelar su pradera en 3D y proporcionar la lista de plantas","og_url":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/","og_site_name":"RhinoLands","article_published_time":"2022-03-31T15:23:28+00:00","article_modified_time":"2022-07-05T11:13:30+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2-1024x576.png","type":"image\/png"}],"author":"Elham Ghabouli","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elham Ghabouli","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/#article","isPartOf":{"@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/"},"author":{"name":"Elham Ghabouli","@id":"https:\/\/rhinolands.com\/es\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea"},"headline":"C\u00f3mo crear una pradera de flores silvestres","datePublished":"2022-03-31T15:23:28+00:00","dateModified":"2022-07-05T11:13:30+00:00","mainEntityOfPage":{"@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/"},"wordCount":377,"publisher":{"@id":"https:\/\/rhinolands.com\/es\/#organization"},"image":{"@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2.png","articleSection":["Conocimientos","formaci\u00f3n","Proyectos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/","url":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/","name":"C\u00f3mo crear una pradera de flores silvestres - RhinoLands","isPartOf":{"@id":"https:\/\/rhinolands.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/#primaryimage"},"image":{"@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2.png","datePublished":"2022-03-31T15:23:28+00:00","dateModified":"2022-07-05T11:13:30+00:00","description":"C\u00f3mo crear una pradera de flores silvestres en su proyecto paisaj\u00edstico o jard\u00edn. Lands Design puede modelar su pradera en 3D y proporcionar la lista de plantas","breadcrumb":{"@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/#primaryimage","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2.png","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/03\/TMScreenshot_2021.12.30-16.42.25-2.png","width":1424,"height":801,"caption":"How to create a wildflower meadow? Lands design landscape 3D design. plant species for meadow"},{"@type":"BreadcrumbList","@id":"https:\/\/rhinolands.com\/es\/post\/como-crear-una-pradera-de-flores-silvestres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhinolands.com\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo crear una pradera de flores silvestres"}]},{"@type":"WebSite","@id":"https:\/\/rhinolands.com\/es\/#website","url":"https:\/\/rhinolands.com\/es\/","name":"RhinoLands","description":"BIM landscape software","publisher":{"@id":"https:\/\/rhinolands.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhinolands.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rhinolands.com\/es\/#organization","name":"Asuni Soft","url":"https:\/\/rhinolands.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rhinolands.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","width":151,"height":46,"caption":"Asuni Soft"},"image":{"@id":"https:\/\/rhinolands.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rhinolands.com\/es\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea","name":"Elham Ghabouli","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","caption":"Elham Ghabouli"}}]}},"_links":{"self":[{"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/posts\/71658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/comments?post=71658"}],"version-history":[{"count":3,"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/posts\/71658\/revisions"}],"predecessor-version":[{"id":72317,"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/posts\/71658\/revisions\/72317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/media\/71660"}],"wp:attachment":[{"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/media?parent=71658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/categories?post=71658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhinolands.com\/es\/wp-json\/wp\/v2\/tags?post=71658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}