{"id":72895,"date":"2022-11-29T12:51:53","date_gmt":"2022-11-29T11:51:53","guid":{"rendered":"https:\/\/rhinolands.com\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/"},"modified":"2022-11-29T13:44:40","modified_gmt":"2022-11-29T12:44:40","slug":"elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages","status":"publish","type":"post","link":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/","title":{"rendered":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages"},"content":{"rendered":"Le prochain webinaire de Lands Design se d\u00e9roulera le 7 d\u00e9cembre \u00e0 16h30 CET \/ 9h30 CST. Il s&rsquo;agit d&rsquo;un <a href=\"https:\/\/laces.asla.org\/Default.aspx\">cours LACES approuv\u00e9<\/a> \u00e9quivalent \u00e0 1,5 heures de PDH. \n\nL&rsquo;objectif de ce webinaire est de pr\u00e9senter un aper\u00e7u du potentiel de Rhino et Lands Design pour l&rsquo;architecture paysag\u00e8re. Cette session couvre les principales fonctions du programme, telles que : outils de cr\u00e9ation et classification de terrains, v\u00e9g\u00e9tation et outils de documentation. Elle offre un aper\u00e7u des fonctions BIM et du flux de travail dans le processus de conception avec le programme. \n<ul>\n \t<li><strong>Titre\u00a0:<\/strong> BIM workflow and landscape modeling with Lands Design<\/li>\n \t<li><strong>Date :<\/strong> 07\/12\/2022<\/li>\n \t<li><strong>Heure :<\/strong> 16h30 CET \/ 9h30 CST<\/li>\n<\/ul>\n<strong>Notez la date<\/strong> et <a href=\"https:\/\/rhinolands.com\/fr\/learn\/webinars\/registration\/?id=83642332123\">inscrivez-vous d\u00e8s maintenant<\/a> !\n\n<a href=\"https:\/\/rhinolands.com\/fr\/learn\/webinars\/registration\/?id=83642332123\"><img loading=\"lazy\" decoding=\"async\" class=\"https:\/\/rhinolands.com\/learn\/webinars\/registration\/?id=83642332123 aligncenter wp-image-72853 size-large\" title=\"https:\/\/rhinolands.com\/learn\/webinars\/registration\/?id=83642332123\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster-1-1024x576.jpg\" alt=\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages \" width=\"1024\" height=\"576\" srcset=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster-1-1024x576.jpg 1024w, https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster-1-980x552.jpg 980w, https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster-1-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a>\n\n&nbsp;","protected":false},"excerpt":{"rendered":"<p>\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages<\/p>\n","protected":false},"author":15,"featured_media":72897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2186,2128],"tags":[2601],"class_list":["post-72895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apprentissage","category-events-fr","tag-webinar-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages - RhinoLands<\/title>\n<meta name=\"description\" content=\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages avec Lands Design dans Rhino, un puissant logiciel BIM pour l&#039;architecture paysag\u00e8re\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages - RhinoLands\" \/>\n<meta property=\"og:description\" content=\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages avec Lands Design dans Rhino, un puissant logiciel BIM pour l&#039;architecture paysag\u00e8re\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/\" \/>\n<meta property=\"og:site_name\" content=\"RhinoLands\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T11:51:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T12:44:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elham Ghabouli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elham Ghabouli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/\"},\"author\":{\"name\":\"Elham Ghabouli\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\"},\"headline\":\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages\",\"datePublished\":\"2022-11-29T11:51:53+00:00\",\"dateModified\":\"2022-11-29T12:44:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/\"},\"wordCount\":136,\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/webinar-poster.jpg\",\"keywords\":[\"Webinaire\"],\"articleSection\":[\"apprentissage\",\"\u00c9v\u00e9nements\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/\",\"name\":\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages - RhinoLands\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/webinar-poster.jpg\",\"datePublished\":\"2022-11-29T11:51:53+00:00\",\"dateModified\":\"2022-11-29T12:44:40+00:00\",\"description\":\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages avec Lands Design dans Rhino, un puissant logiciel BIM pour l'architecture paysag\u00e8re\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/webinar-poster.jpg\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/webinar-poster.jpg\",\"width\":1160,\"height\":653,\"caption\":\"Achieve a new skill: webinar of BIM and landscape modeling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/post\\\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/\",\"name\":\"RhinoLands\",\"description\":\"BIM landscape software\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#organization\",\"name\":\"Asuni Soft\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"width\":151,\"height\":46,\"caption\":\"Asuni Soft\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/fr\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\",\"name\":\"Elham Ghabouli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"caption\":\"Elham Ghabouli\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages - RhinoLands","description":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages avec Lands Design dans Rhino, un puissant logiciel BIM pour l'architecture paysag\u00e8re","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages - RhinoLands","og_description":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages avec Lands Design dans Rhino, un puissant logiciel BIM pour l'architecture paysag\u00e8re","og_url":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/","og_site_name":"RhinoLands","article_published_time":"2022-11-29T11:51:53+00:00","article_modified_time":"2022-11-29T12:44:40+00:00","og_image":[{"width":1160,"height":653,"url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster.jpg","type":"image\/jpeg"}],"author":"Elham Ghabouli","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Elham Ghabouli","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/#article","isPartOf":{"@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/"},"author":{"name":"Elham Ghabouli","@id":"https:\/\/rhinolands.com\/fr\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea"},"headline":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages","datePublished":"2022-11-29T11:51:53+00:00","dateModified":"2022-11-29T12:44:40+00:00","mainEntityOfPage":{"@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/"},"wordCount":136,"publisher":{"@id":"https:\/\/rhinolands.com\/fr\/#organization"},"image":{"@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster.jpg","keywords":["Webinaire"],"articleSection":["apprentissage","\u00c9v\u00e9nements"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/","url":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/","name":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages - RhinoLands","isPartOf":{"@id":"https:\/\/rhinolands.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/#primaryimage"},"image":{"@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster.jpg","datePublished":"2022-11-29T11:51:53+00:00","dateModified":"2022-11-29T12:44:40+00:00","description":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages avec Lands Design dans Rhino, un puissant logiciel BIM pour l'architecture paysag\u00e8re","breadcrumb":{"@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/#primaryimage","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster.jpg","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/11\/webinar-poster.jpg","width":1160,"height":653,"caption":"Achieve a new skill: webinar of BIM and landscape modeling"},{"@type":"BreadcrumbList","@id":"https:\/\/rhinolands.com\/fr\/post\/elargissez-vos-competences-webinaire-sur-le-bim-et-la-modelisation-de-paysages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhinolands.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9largissez vos comp\u00e9tences : webinaire sur le BIM et la mod\u00e9lisation de paysages"}]},{"@type":"WebSite","@id":"https:\/\/rhinolands.com\/fr\/#website","url":"https:\/\/rhinolands.com\/fr\/","name":"RhinoLands","description":"BIM landscape software","publisher":{"@id":"https:\/\/rhinolands.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhinolands.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rhinolands.com\/fr\/#organization","name":"Asuni Soft","url":"https:\/\/rhinolands.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rhinolands.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","width":151,"height":46,"caption":"Asuni Soft"},"image":{"@id":"https:\/\/rhinolands.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rhinolands.com\/fr\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea","name":"Elham Ghabouli","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","caption":"Elham Ghabouli"}}]}},"_links":{"self":[{"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/posts\/72895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/comments?post=72895"}],"version-history":[{"count":1,"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/posts\/72895\/revisions"}],"predecessor-version":[{"id":72905,"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/posts\/72895\/revisions\/72905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/media\/72897"}],"wp:attachment":[{"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/media?parent=72895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/categories?post=72895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhinolands.com\/fr\/wp-json\/wp\/v2\/tags?post=72895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}