{"id":73149,"date":"2022-12-27T12:41:37","date_gmt":"2022-12-27T11:41:37","guid":{"rendered":"https:\/\/rhinolands.com\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/"},"modified":"2022-12-27T12:41:37","modified_gmt":"2022-12-27T11:41:37","slug":"il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio","status":"publish","type":"post","link":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/","title":{"rendered":"Il nuovo anno inizia con un nuovo webinar a gennaio"},"content":{"rendered":"ASUNI vi augura un prospero anno nuovo!\n\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-73149-1\" width=\"640\" height=\"640\" autoplay preload=\"auto\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/Xmas-LandsDesign-2023.mp4?_=1\" \/><a href=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/Xmas-LandsDesign-2023.mp4\">https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/Xmas-LandsDesign-2023.mp4<\/a><\/video><\/div>\n\n&nbsp;\n\nPer iniziare il nuovo anno con una marcia in pi\u00f9, abbiamo organizzato una nuova <a href=\"https:\/\/laces.asla.org\/visitor\/CourseDetails.aspx?CourseID=47561\">sessione formativa online<\/a>, in collaborazione con LA CES, ASLA. L&#8217;iscrizione \u00e8 gratuita ed aperta a tutti.Il webinar si terr\u00e0 l&#8217;11 gennaio alle ore 16:30 CET (09:30 Central USA). Si tratta di un <a href=\"https:\/\/laces.asla.org\/visitor\/CourseDetails.aspx?CourseID=47561\">corso LACES<\/a> della durata di 1,5 ore. L&#8217;obiettivo di questo webinar \u00e8 fornire una panoramica sulle potenzialit\u00e0 di Rhino e Lands Design nel settore del paesaggismo. La sessione si incentra sulle principali funzionalit\u00e0 del software, tra cui: strumenti terreno e livellamento, vegetazione e documentazione. Verranno presentate le funzionalit\u00e0 e il flusso di lavoro BIM nel processo di modellazione in Lands Design.\n<ul>\n \t<li><strong>Titolo:<\/strong> BIM workflow and landscape modeling with Lands Design<\/li>\n \t<li><strong>Data:<\/strong> 11\/01\/2023<\/li>\n \t<li><strong>Ora:<\/strong> 16:30 CET (09:30 UTC)<\/li>\n<\/ul>\n<strong><\/strong> <a href=\"https:\/\/rhinolands.com\/it\/learn\/webinars\/registration\/?id=81557398750\">iscriviti<\/a>!\n\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-73121 size-full\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png\" alt=\"sessione gratuita - webinar sul software 3D di paesaggismo\" width=\"932\" height=\"594\" srcset=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png 932w, https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla-480x306.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 932px, 100vw\" \/>","protected":false},"excerpt":{"rendered":"<p>ASUNI vi augura un prospero anno nuovo! &nbsp; Per iniziare il nuovo anno con una marcia in pi\u00f9, abbiamo organizzato una nuova sessione formativa online, in collaborazione con LA CES, ASLA. L&#8217;iscrizione \u00e8 gratuita ed aperta a tutti.Il webinar si terr\u00e0 l&#8217;11 gennaio alle ore 16:30 CET (09:30 Central USA). Si tratta di un corso [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":73151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2138,2177],"tags":[2553,2593],"class_list":["post-73149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-it","category-formazione","tag-events-it","tag-training-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il nuovo anno inizia con un nuovo webinar a gennaio - RhinoLands<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il nuovo anno inizia con un nuovo webinar a gennaio - RhinoLands\" \/>\n<meta property=\"og:description\" content=\"ASUNI vi augura un prospero anno nuovo! &nbsp; Per iniziare il nuovo anno con una marcia in pi\u00f9, abbiamo organizzato una nuova sessione formativa online, in collaborazione con LA CES, ASLA. L&#8217;iscrizione \u00e8 gratuita ed aperta a tutti.Il webinar si terr\u00e0 l&#8217;11 gennaio alle ore 16:30 CET (09:30 Central USA). Si tratta di un corso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/\" \/>\n<meta property=\"og:site_name\" content=\"RhinoLands\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-27T11:41:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png\" \/>\n\t<meta property=\"og:image:width\" content=\"932\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elham Ghabouli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elham Ghabouli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/\"},\"author\":{\"name\":\"Elham Ghabouli\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\"},\"headline\":\"Il nuovo anno inizia con un nuovo webinar a gennaio\",\"datePublished\":\"2022-12-27T11:41:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/\"},\"wordCount\":153,\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/webinar-11-enero-2023-asla.png\",\"keywords\":[\"Eventi\",\"Formazione\"],\"articleSection\":[\"Eventi\",\"formazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/\",\"name\":\"Il nuovo anno inizia con un nuovo webinar a gennaio - RhinoLands\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/webinar-11-enero-2023-asla.png\",\"datePublished\":\"2022-12-27T11:41:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/webinar-11-enero-2023-asla.png\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/webinar-11-enero-2023-asla.png\",\"width\":932,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il nuovo anno inizia con un nuovo webinar a gennaio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/\",\"name\":\"RhinoLands\",\"description\":\"BIM landscape software\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#organization\",\"name\":\"Asuni Soft\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"width\":151,\"height\":46,\"caption\":\"Asuni Soft\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\",\"name\":\"Elham Ghabouli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"caption\":\"Elham Ghabouli\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il nuovo anno inizia con un nuovo webinar a gennaio - RhinoLands","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/","og_locale":"it_IT","og_type":"article","og_title":"Il nuovo anno inizia con un nuovo webinar a gennaio - RhinoLands","og_description":"ASUNI vi augura un prospero anno nuovo! &nbsp; Per iniziare il nuovo anno con una marcia in pi\u00f9, abbiamo organizzato una nuova sessione formativa online, in collaborazione con LA CES, ASLA. L&#8217;iscrizione \u00e8 gratuita ed aperta a tutti.Il webinar si terr\u00e0 l&#8217;11 gennaio alle ore 16:30 CET (09:30 Central USA). Si tratta di un corso [&hellip;]","og_url":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/","og_site_name":"RhinoLands","article_published_time":"2022-12-27T11:41:37+00:00","og_image":[{"width":932,"height":594,"url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png","type":"image\/png"}],"author":"Elham Ghabouli","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Elham Ghabouli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/#article","isPartOf":{"@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/"},"author":{"name":"Elham Ghabouli","@id":"https:\/\/rhinolands.com\/it\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea"},"headline":"Il nuovo anno inizia con un nuovo webinar a gennaio","datePublished":"2022-12-27T11:41:37+00:00","mainEntityOfPage":{"@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/"},"wordCount":153,"publisher":{"@id":"https:\/\/rhinolands.com\/it\/#organization"},"image":{"@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png","keywords":["Eventi","Formazione"],"articleSection":["Eventi","formazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/","url":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/","name":"Il nuovo anno inizia con un nuovo webinar a gennaio - RhinoLands","isPartOf":{"@id":"https:\/\/rhinolands.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/#primaryimage"},"image":{"@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png","datePublished":"2022-12-27T11:41:37+00:00","breadcrumb":{"@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/#primaryimage","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2022\/12\/webinar-11-enero-2023-asla.png","width":932,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/rhinolands.com\/it\/post\/il-nuovo-anno-inizia-con-un-nuovo-webinar-a-gennaio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhinolands.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il nuovo anno inizia con un nuovo webinar a gennaio"}]},{"@type":"WebSite","@id":"https:\/\/rhinolands.com\/it\/#website","url":"https:\/\/rhinolands.com\/it\/","name":"RhinoLands","description":"BIM landscape software","publisher":{"@id":"https:\/\/rhinolands.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhinolands.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/rhinolands.com\/it\/#organization","name":"Asuni Soft","url":"https:\/\/rhinolands.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rhinolands.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","width":151,"height":46,"caption":"Asuni Soft"},"image":{"@id":"https:\/\/rhinolands.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rhinolands.com\/it\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea","name":"Elham Ghabouli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","caption":"Elham Ghabouli"}}]}},"_links":{"self":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/posts\/73149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/comments?post=73149"}],"version-history":[{"count":0,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/posts\/73149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/media\/73151"}],"wp:attachment":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/media?parent=73149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/categories?post=73149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/tags?post=73149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}