{"id":81212,"date":"2024-04-17T13:43:25","date_gmt":"2024-04-17T11:43:25","guid":{"rendered":"https:\/\/rhinolands.com\/post\/release-di-lands-design-6-rhinolands\/"},"modified":"2024-05-16T12:44:23","modified_gmt":"2024-05-16T10:44:23","slug":"release-di-lands-design-6-rhinolands","status":"publish","type":"post","link":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/","title":{"rendered":"Approfitta della promozione per l&#8217;aggiornamento di Lands Design 6!"},"content":{"rendered":"\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-wide\"\/>\n\n<h2 class=\"wp-block-heading has-text-align-center\"> <\/h2>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/rhinolands.com\/it\/post\/tecnologia-bim-in-paesaggismo\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/05\/Rhinolands-enews-2-1024x576.png\" alt=\"\" class=\"wp-image-81824\" srcset=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/05\/Rhinolands-enews-2-980x551.png 980w, https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/05\/Rhinolands-enews-2-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong>Caro utente,<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">Siamo lieti di annunciare la <strong>versione 6 di Lands Design<\/strong> che include nuove funzionalit\u00e0 e miglioramenti.<\/p>\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">Inoltre, siamo felici di poter lanciare sul mercato un nuovo prodotto:\u00a0<strong>RhinoLands<\/strong>. Questo pacchetto combina Rhino e Lands Design in una soluzione standalone, con un&#8217;<strong>interfaccia usabile<\/strong>\u00a0che include Rhino.<\/p>\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">Se disponi gi\u00e0 di una licenza di Rhino 8 (o Rhino 7), puoi approfittare di questa <strong>offerta lancio<\/strong> per l&#8217;aggiornamento di Lands Design 6.<\/p>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-wide\"\/>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-wide\"\/>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h2 class=\"wp-block-heading\">Approfitta della promozione per l&#8217;aggiornamento<\/h2>\n\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\">Aggiorna il software e libera le infinite possibilit\u00e0 che offre per il tuo prossimo capolavoro!\u00a0Tutti gli aggiornamenti prevedono un&#8217; <strong>offerta lancio<\/strong>\u00a0fino al <strong>28 giugno 2024<\/strong>.<\/p>\n\n<ul class=\"wp-block-list\">\n<li style=\"font-size:14px\">Lands Design 6 &#8211;  Aggiornamento versione commerciale:\u00a0<s>475<\/s><strong>\u00a0325<\/strong>\u20ac\/$\u00a0<\/li>\n\n\n\n<li style=\"font-size:14px\">RhinoLands &#8211; Aggiornamento versione commerciale:\u00a0<s>1070<\/s>\u00a0<strong>920<\/strong>\u20ac\/$\u00a0(aggiornamento a Rhino 8 incluso).<\/li>\n\n\n\n<li style=\"font-size:14px\">Lands Design 6 &#8211;  Aggiornamento versione Educational:\u00a0<strong>55\u00a0<\/strong>\u20ac\/$<\/li>\n\n\n\n<li style=\"font-size:14px\">RhinoLands &#8211; Aggiornamento versione Educational:\u00a0<strong>150<\/strong>\u00a0\u20ac\/$\u00a0(aggiornamento a Rhino 8 incluso).<\/li>\n<\/ul>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/rhinolands.com\/it\/sales\/\" style=\"border-radius:4px;background-color:#307e11\"><strong>Aggiorna ora<\/strong><\/a><\/div>\n<\/div>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-wide\"\/>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-wide\"\/>\n\n<figure class=\"wp-block-image size-large\"><a href=\"rhinolands.com\/features\/whats-new\/#DisplayNewFeatures\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"523\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/05\/display-RhinoLands-1024x523.png\" alt=\"\" class=\"wp-image-81826\" srcset=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/05\/display-RhinoLands-980x500.png 980w, https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/05\/display-RhinoLands-480x245.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><figcaption class=\"wp-element-caption\">Imposta varie modalit\u00e0 di visualizzazione su ciascuna vista<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Alcune nuove funzionalit\u00e0:<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/#RhinolandsInterface\" target=\"_blank\" rel=\"noreferrer noopener\">Soluzione standalone con interfaccia semplificata.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/#NewTools\" target=\"_blank\" rel=\"noreferrer noopener\">Rampa parametrica intelligente.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/#Terrain\" target=\"_blank\" rel=\"noreferrer noopener\">Importazione di strade 2D.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/#Terrain\" target=\"_blank\" rel=\"noreferrer noopener\">Numerosi miglioramenti alle operazioni del terreno.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/#DisplayNewFeatures\" target=\"_blank\" rel=\"noreferrer noopener\">Nuova funzione di visualizzazione: viste 2D\/3D indipendenti.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/#EnhancedPlantingPlanFeatures\" target=\"_blank\" rel=\"noreferrer noopener\">Funzionalit\u00e0 del piano di piantagione migliorate.<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/#DocumentationImprovements\" target=\"_blank\" rel=\"noreferrer noopener\">Nuovi strumenti di documentazione: marcatore livelli, elenco di muri, steccati e sentieri.<\/a><\/li>\n<\/ul>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/rhinolands.com\/it\/features\/whats-new\/\" style=\"border-radius:4px;background-color:#307e11\"><strong>Consulta tutte le nuove funzionalit\u00e0<\/strong><\/a><\/div>\n<\/div>\n\n<figure class=\"wp-block-image size-full\"><a href=\"rhinolands.com\/features\/whats-new\/#EnhancedPlantingPlanFeatures\"><img loading=\"lazy\" decoding=\"async\" width=\"892\" height=\"648\" src=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/05\/Hatch-and-merge-crown-option-in-RhinoLands-6.gif\" alt=\"\" class=\"wp-image-81827\"\/><\/a><figcaption class=\"wp-element-caption\">Nuovi simboli delle piante con pi\u00f9 opzioni: unione di corone, attivazione dei riempimenti e modifica del colore dei contorni.<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<h6 class=\"wp-block-heading has-text-align-center\"><strong>Dubbi?\u00a0<a href=\"mailto:rhinolands@asuni.com?subject=Questions%20about%20Lands%20Design%20Upgrade\" target=\"_blank\" rel=\"noreferrer noopener\">Contattaci<\/a>.<\/strong><br\/><a href=\"https:\/\/rhinolands.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.rhinolands.com\/it<\/a><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Caro utente, Siamo lieti di annunciare la versione 6 di Lands Design che include nuove funzionalit\u00e0 e miglioramenti. Inoltre, siamo felici di poter lanciare sul mercato un nuovo prodotto:\u00a0RhinoLands. Questo pacchetto combina Rhino e Lands Design in una soluzione standalone, con un&#8217;interfaccia usabile\u00a0che include Rhino. Se disponi gi\u00e0 di una licenza di Rhino 8 (o [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":81278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2535],"tags":[],"class_list":["post-81212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Approfitta della promozione per l&#039;aggiornamento di Lands Design 6! - RhinoLands<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Approfitta della promozione per l&#039;aggiornamento di Lands Design 6! - RhinoLands\" \/>\n<meta property=\"og:description\" content=\"Caro utente, Siamo lieti di annunciare la versione 6 di Lands Design che include nuove funzionalit\u00e0 e miglioramenti. Inoltre, siamo felici di poter lanciare sul mercato un nuovo prodotto:\u00a0RhinoLands. Questo pacchetto combina Rhino e Lands Design in una soluzione standalone, con un&#8217;interfaccia usabile\u00a0che include Rhino. Se disponi gi\u00e0 di una licenza di Rhino 8 (o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/\" \/>\n<meta property=\"og:site_name\" content=\"RhinoLands\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T11:43:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-16T10:44:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/04\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1267\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elham Ghabouli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elham Ghabouli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/\"},\"author\":{\"name\":\"Elham Ghabouli\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\"},\"headline\":\"Approfitta della promozione per l&#8217;aggiornamento di Lands Design 6!\",\"datePublished\":\"2024-04-17T11:43:25+00:00\",\"dateModified\":\"2024-05-16T10:44:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/\"},\"wordCount\":226,\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png\",\"articleSection\":[\"Newsletter\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/\",\"name\":\"Approfitta della promozione per l'aggiornamento di Lands Design 6! - RhinoLands\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png\",\"datePublished\":\"2024-04-17T11:43:25+00:00\",\"dateModified\":\"2024-05-16T10:44:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png\",\"width\":1267,\"height\":714},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/post\\\/release-di-lands-design-6-rhinolands\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Approfitta della promozione per l&#8217;aggiornamento di Lands Design 6!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/\",\"name\":\"RhinoLands\",\"description\":\"BIM landscape software\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#organization\",\"name\":\"Asuni Soft\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"contentUrl\":\"https:\\\/\\\/rhinolands.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/AsuniLogoFinal-01.png\",\"width\":151,\"height\":46,\"caption\":\"Asuni Soft\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rhinolands.com\\\/it\\\/#\\\/schema\\\/person\\\/4360b7851e82049e4a3c393564a5e5ea\",\"name\":\"Elham Ghabouli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g\",\"caption\":\"Elham Ghabouli\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Approfitta della promozione per l'aggiornamento di Lands Design 6! - RhinoLands","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/","og_locale":"it_IT","og_type":"article","og_title":"Approfitta della promozione per l'aggiornamento di Lands Design 6! - RhinoLands","og_description":"Caro utente, Siamo lieti di annunciare la versione 6 di Lands Design che include nuove funzionalit\u00e0 e miglioramenti. Inoltre, siamo felici di poter lanciare sul mercato un nuovo prodotto:\u00a0RhinoLands. Questo pacchetto combina Rhino e Lands Design in una soluzione standalone, con un&#8217;interfaccia usabile\u00a0che include Rhino. Se disponi gi\u00e0 di una licenza di Rhino 8 (o [&hellip;]","og_url":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/","og_site_name":"RhinoLands","article_published_time":"2024-04-17T11:43:25+00:00","article_modified_time":"2024-05-16T10:44:23+00:00","og_image":[{"width":1267,"height":714,"url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/04\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png","type":"image\/png"}],"author":"Elham Ghabouli","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Elham Ghabouli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/#article","isPartOf":{"@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/"},"author":{"name":"Elham Ghabouli","@id":"https:\/\/rhinolands.com\/it\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea"},"headline":"Approfitta della promozione per l&#8217;aggiornamento di Lands Design 6!","datePublished":"2024-04-17T11:43:25+00:00","dateModified":"2024-05-16T10:44:23+00:00","mainEntityOfPage":{"@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/"},"wordCount":226,"publisher":{"@id":"https:\/\/rhinolands.com\/it\/#organization"},"image":{"@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/04\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png","articleSection":["Newsletter"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/","url":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/","name":"Approfitta della promozione per l'aggiornamento di Lands Design 6! - RhinoLands","isPartOf":{"@id":"https:\/\/rhinolands.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/#primaryimage"},"image":{"@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/04\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png","datePublished":"2024-04-17T11:43:25+00:00","dateModified":"2024-05-16T10:44:23+00:00","breadcrumb":{"@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/#primaryimage","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/04\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2024\/04\/f656ef06-3781-ef8a-87c3-9d41f4e1897c.png","width":1267,"height":714},{"@type":"BreadcrumbList","@id":"https:\/\/rhinolands.com\/it\/post\/release-di-lands-design-6-rhinolands\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhinolands.com\/it\/"},{"@type":"ListItem","position":2,"name":"Approfitta della promozione per l&#8217;aggiornamento di Lands Design 6!"}]},{"@type":"WebSite","@id":"https:\/\/rhinolands.com\/it\/#website","url":"https:\/\/rhinolands.com\/it\/","name":"RhinoLands","description":"BIM landscape software","publisher":{"@id":"https:\/\/rhinolands.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhinolands.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/rhinolands.com\/it\/#organization","name":"Asuni Soft","url":"https:\/\/rhinolands.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rhinolands.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","contentUrl":"https:\/\/rhinolands.com\/wp-content\/uploads\/2020\/02\/AsuniLogoFinal-01.png","width":151,"height":46,"caption":"Asuni Soft"},"image":{"@id":"https:\/\/rhinolands.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rhinolands.com\/it\/#\/schema\/person\/4360b7851e82049e4a3c393564a5e5ea","name":"Elham Ghabouli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a25a87920abb99dc6a3599f12fc35665d17170c8b70facdb678073c66193c73?s=96&d=mm&r=g","caption":"Elham Ghabouli"}}]}},"_links":{"self":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/posts\/81212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/comments?post=81212"}],"version-history":[{"count":3,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/posts\/81212\/revisions"}],"predecessor-version":[{"id":81843,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/posts\/81212\/revisions\/81843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/media\/81278"}],"wp:attachment":[{"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/media?parent=81212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/categories?post=81212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rhinolands.com\/it\/wp-json\/wp\/v2\/tags?post=81212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}